{"id":196,"date":"2019-06-06T21:58:36","date_gmt":"2019-06-06T19:58:36","guid":{"rendered":"http:\/\/wordpress.brunski.de\/wordpress\/?p=196"},"modified":"2019-06-06T21:58:41","modified_gmt":"2019-06-06T19:58:41","slug":"vorteile-einer-baustellentuer-waehrend-der-bauphase","status":"publish","type":"post","link":"http:\/\/wordpress.brunski.de\/wordpress\/2019\/06\/06\/vorteile-einer-baustellentuer-waehrend-der-bauphase\/","title":{"rendered":"Vorteile einer Baustellent\u00fcr w\u00e4hrend der Bauphase"},"content":{"rendered":"\n<p>Baustellent\u00fcren \u00fcbernehmen w\u00e4hrend der Bauphase gleich mehrere wichtige Aufgaben. Einerseits gew\u00e4hrleisten sie die volle Zutrittskontrolle, andererseits sch\u00fctzen sie die eigentliche Haupteingangst\u00fcr vor Besch\u00e4diungen w\u00e4hrend der Bauphase. <\/p>\n\n\n\n<p><strong>Zutrittskontrolle: <\/strong><br>Ist der Eingangsbereich ohne tempor\u00e4re Zugangsbeschr\u00e4nkung, so stellt dies f\u00f6rmlich eine Einladung f\u00fcr alle vorbeigehen Menschen dar, sich die Baustelle anzusehen. Dabei geht es hier vor allem auch um den Schutz vor Vandalismus, Diebstahl und ganz wichtig auch um ihre eigene Rechtssicherheit. Man vermeidet unangenehme Situationen, da Unbefugte (wie z.B. spielende Kinder) keinen Zutritt mehr erlangen und sich so auch nicht auf der Baustelle verletzen k\u00f6nnen. Sie kommen somit ihrer Pflicht als verantwortungsvoller Bauherr nach. <\/p>\n\n\n\n<p><strong>Schutz vor Besch\u00e4digungen: <\/strong><br>Den zweiten wichtigen Punkt stellt der Schutz der eigentlichen Eingangst\u00fcr da. Die oft sehr teure Haust\u00fcr muss w\u00e4hrend der Bauphase aufwendig gesch\u00fctzt werden. Hierbei wird sie oft mit Folie abgeklebt. Jedoch sch\u00fctzt keine Folie vor mechanischen Besch\u00e4digungen (wie zum  Beispiel vor Kratzern oder Dellen durch Werkzeuge). Je mehr Handwerker  jeden Tag ein- und ausgehen, desto h\u00f6her ist das Risiko einer Besch\u00e4digung. Vor allem bei hochwertigen Aluminiumt\u00fcren ist eine Reparatur oft nicht m\u00f6glich. Dann ist ein kompletter Tausch des  T\u00fcrfl\u00fcgels notwendig und bringt neben zus\u00e4tzlichen Kosten eine Menge \u00c4rger und ggf. Bauverz\u00f6gerungen mit sich. <\/p>\n\n\n\n<p style=\"text-align:left\">Wollen auch Sie die Vorteile einer Baustellent\u00fcr nutzen? Dann empfehle ich empfehle ich diesen Link: <\/p>\n\n\n\n<p style=\"text-align:center\"><a href=\"https:\/\/www.ipb-profile.de\/ipb-baustellent%C3%BCr\/\">Baustellent\u00fcr aus Holz<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baustellent\u00fcren \u00fcbernehmen w\u00e4hrend der Bauphase gleich mehrere wichtige Aufgaben. Einerseits gew\u00e4hrleisten sie die volle Zutrittskontrolle, andererseits sch\u00fctzen sie die eigentliche Haupteingangst\u00fcr vor Besch\u00e4diungen w\u00e4hrend der Bauphase. Zutrittskontrolle: Ist der Eingangsbereich ohne tempor\u00e4re Zugangsbeschr\u00e4nkung, so stellt dies f\u00f6rmlich eine Einladung f\u00fcr &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"more-link\" href=\"http:\/\/wordpress.brunski.de\/wordpress\/2019\/06\/06\/vorteile-einer-baustellentuer-waehrend-der-bauphase\/\"> <span class=\"screen-reader-text\">Vorteile einer Baustellent\u00fcr w\u00e4hrend der Bauphase<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[24,23,27,28,29,22,30,26,31],"class_list":["post-196","post","type-post","status-publish","format-standard","hentry","category-die-montagezarge-optizarge","tag-bau","tag-bauherren","tag-baustellen","tag-baustellentuer","tag-geld-sparen-am-bau","tag-hilfe-am-bau","tag-montagezarge","tag-neubau","tag-optizarge"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/posts\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":1,"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"predecessor-version":[{"id":197,"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/posts\/196\/revisions\/197"}],"wp:attachment":[{"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wordpress.brunski.de\/wordpress\/wp-json\/wp\/v2\/tags?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}